{"id":210,"count":3,"description":"","link":"https:\/\/waka-waka.com\/nl\/products\/accessoires\/","name":"Accessoires","slug":"accessoires","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":3,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Accessoires Archives | WakaWaka\u00ae - Share the Sun<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/waka-waka.com\/nl\/products\/accessoires\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accessoires Archives | WakaWaka\u00ae - Share the Sun\" \/>\n<meta property=\"og:url\" content=\"https:\/\/waka-waka.com\/nl\/products\/accessoires\/\" \/>\n<meta property=\"og:site_name\" content=\"WakaWaka\u00ae - Share the Sun\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/waka-waka.com\\\/nl\\\/products\\\/accessoires\\\/\",\"url\":\"https:\\\/\\\/waka-waka.com\\\/nl\\\/products\\\/accessoires\\\/\",\"name\":\"Accessoires Archives | WakaWaka\u00ae - Share the Sun\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/waka-waka.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/waka-waka.com\\\/nl\\\/products\\\/accessoires\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/waka-waka.com\\\/nl\\\/products\\\/accessoires\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/waka-waka.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accessoires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/waka-waka.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/waka-waka.com\\\/de\\\/\",\"name\":\"WakaWaka\u00ae - Share the Sun\",\"description\":\"Share the Sun\",\"publisher\":{\"@id\":\"https:\\\/\\\/waka-waka.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/waka-waka.com\\\/de\\\/search\\\/{search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/waka-waka.com\\\/de\\\/#organization\",\"name\":\"WakaWaka\",\"url\":\"https:\\\/\\\/waka-waka.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/waka-waka.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/waka-waka.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/seo-logo.png\",\"contentUrl\":\"https:\\\/\\\/waka-waka.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/seo-logo.png\",\"width\":484,\"height\":186,\"caption\":\"WakaWaka\"},\"image\":{\"@id\":\"https:\\\/\\\/waka-waka.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accessoires Archives | WakaWaka\u00ae - Share the Sun","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/waka-waka.com\/nl\/products\/accessoires\/","og_locale":"nl_NL","og_type":"article","og_title":"Accessoires Archives | WakaWaka\u00ae - Share the Sun","og_url":"https:\/\/waka-waka.com\/nl\/products\/accessoires\/","og_site_name":"WakaWaka\u00ae - Share the Sun","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/waka-waka.com\/nl\/products\/accessoires\/","url":"https:\/\/waka-waka.com\/nl\/products\/accessoires\/","name":"Accessoires Archives | WakaWaka\u00ae - Share the Sun","isPartOf":{"@id":"https:\/\/waka-waka.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/waka-waka.com\/nl\/products\/accessoires\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/waka-waka.com\/nl\/products\/accessoires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/waka-waka.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Accessoires"}]},{"@type":"WebSite","@id":"https:\/\/waka-waka.com\/de\/#website","url":"https:\/\/waka-waka.com\/de\/","name":"WakaWaka\u00ae - Share the Sun","description":"Share the Sun","publisher":{"@id":"https:\/\/waka-waka.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/waka-waka.com\/de\/search\/{search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/waka-waka.com\/de\/#organization","name":"WakaWaka","url":"https:\/\/waka-waka.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/waka-waka.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/waka-waka.com\/wp-content\/uploads\/2019\/10\/seo-logo.png","contentUrl":"https:\/\/waka-waka.com\/wp-content\/uploads\/2019\/10\/seo-logo.png","width":484,"height":186,"caption":"WakaWaka"},"image":{"@id":"https:\/\/waka-waka.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/waka-waka.com\/nl\/wp-json\/wp\/v2\/product_cat\/210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/waka-waka.com\/nl\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/waka-waka.com\/nl\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/waka-waka.com\/nl\/wp-json\/wp\/v2\/product?product_cat=210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}